{"id":1072,"date":"2022-09-10T13:36:21","date_gmt":"2022-09-10T11:36:21","guid":{"rendered":"https:\/\/host-unlimited.de\/blog\/?p=1072"},"modified":"2022-09-10T13:58:37","modified_gmt":"2022-09-10T11:58:37","slug":"weitergabe-von-transaktionskosten-statt-satten-preiserhoehungen-bei-host-unlimited-de","status":"publish","type":"post","link":"https:\/\/host-unlimited.de\/blog\/weitergabe-von-transaktionskosten-statt-satten-preiserhoehungen-bei-host-unlimited-de\/","title":{"rendered":"Weitergabe von Transaktionskosten statt satten Preiserh\u00f6hungen bei Host-Unlimited.de"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Leider ist auch Host-Unlimited.de von der rasenden Inflation in Deutschland betroffen. H\u00f6here Personalkosten, Mieten und vor allem extrem h\u00f6heren Stromkosten sowie der unglaublich starke Dollar (h\u00f6here Einkaufspreise f\u00fcr Server und Ersatzteile) treffen auch uns als Vermieter von Rechenleistung hart. So hart, dass wir diese Kosten nicht einfach &#8222;schlucken&#8220; k\u00f6nnen. Bereits 2020 stieg die Inflationsrate und unsere Kosten stiegen, doch wir \u00fcbernahmen diese Mehrkosten f\u00fcr unsere Kunden in der schweren Corona Zeit und glichen dies auch durch deutlich mehr Umsatz (H\u00f6here Nachfrage w\u00e4hrend der Lockdowns) aus. So ein Ausgleich ist jetzt aber nicht m\u00f6glich. Die Nachfrage l\u00e4sst nach, die Kunden investieren vorsichtiger und die Kosten steigen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir konnten in den letzten 12 Jahren regelm\u00e4\u00dfig unsere Leistung steigern und dazu Preise sogar durch immer h\u00f6here Effizienz der Serverfarm und Optimierungen in unseren Abl\u00e4ufen weiter senken.<strong> Es gab  in 12 Jahren keine Preiserh\u00f6hung bei uns.<\/strong> Dieser Trend kann aber aktuell nicht wie bisher fortgesetzt werden. Es ist schlicht unm\u00f6glich, wenn wir wirtschaftlich bleiben wollen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir m\u00fcssten jetzt s\u00e4mtliche Preise anheben (Keine Sorge, wir konnten das vor\u00fcbergehend noch abwenden, dazu sp\u00e4ter mehr). In einigen Bereichen mit besonders geringer Gewinnmarge haben wir die Preise leicht f\u00fcr Neukunden bereits angehoben. Vor allem dedizierte Server sind dadurch teurer geworden. Im Massengesch\u00e4ft (vServer und Gameserver) konnten wir diesen Schritt bisher aber vermeiden. Lediglich die Rabatte f\u00fcr Vorauszahler haben wir dort etwas reduziert. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da wir aber dennoch reagieren m\u00fcssen, um wirtschaftlich zu bleiben, m\u00fcssen wir k\u00fcnftig Kunden dazu bewegen, auf g\u00fcnstige oder kostenlose Zahlungsarten umzusteigen. Manche Zahlungsarten kosten uns als H\u00e4ndler bis zu 15 % Geb\u00fchren und das \u00fcbersteigt bei manchen Produkten unsere ohnehin schon sehr geringe Marge in dieser schwierigen Zeit.  \u00dcber 12 Jahre lang haben wir diese Geb\u00fchren f\u00fcr unsere Kunden stillschweigend \u00fcbernommen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir haben uns daher dazu entschieden, vorerst als Kostenkompensation statt weiteren Preiserh\u00f6hungen die hohen Transaktionsgeb\u00fchren durchzureichen. Da wir weiterhin auch kostenlose Zahlungsarten anbieten, k\u00f6nnen Kunden diese indirekte Preiserh\u00f6hung also umgehen. Die Kunden zahlen (noch) den gleichen Preis und wir k\u00f6nnen bis zu 15 % mehr vom Umsatz behalten, wenn Kunden Ihr Zahlverhalten \u00e4ndern und damit aktuelle Mehrkosten bezahlen. Wir reichen die Transaktionsgeb\u00fchren ohne Aufschl\u00e4ge durch. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sind der Meinung, dass dies eine faire L\u00f6sung f\u00fcr alle ist und hoffen auf Euer Verst\u00e4ndnis und Eure Unterst\u00fctzung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dies ist aber keine Zusage, dass wir nicht doch zus\u00e4tzlich auch die Preise in der n\u00e4chsten Zeit anheben m\u00fcssen &#8211; vor allem &#8211; wenn es wahr werden sollte, dass der Strompreis sich nochmals verdoppelt oder gar verdreifacht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leider ist auch Host-Unlimited.de von der rasenden Inflation in Deutschland betroffen. H\u00f6here Personalkosten, Mieten und vor allem extrem h\u00f6heren Stromkosten sowie der unglaublich starke Dollar (h\u00f6here Einkaufspreise f\u00fcr Server und Ersatzteile) treffen auch uns als Vermieter von Rechenleistung hart. So hart, dass wir diese Kosten nicht einfach &#8222;schlucken&#8220; k\u00f6nnen. Bereits 2020 stieg die Inflationsrate und &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/host-unlimited.de\/blog\/weitergabe-von-transaktionskosten-statt-satten-preiserhoehungen-bei-host-unlimited-de\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eWeitergabe von Transaktionskosten statt satten Preiserh\u00f6hungen bei Host-Unlimited.de\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1072","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/host-unlimited.de\/blog\/wp-json\/wp\/v2\/posts\/1072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/host-unlimited.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/host-unlimited.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/host-unlimited.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/host-unlimited.de\/blog\/wp-json\/wp\/v2\/comments?post=1072"}],"version-history":[{"count":15,"href":"https:\/\/host-unlimited.de\/blog\/wp-json\/wp\/v2\/posts\/1072\/revisions"}],"predecessor-version":[{"id":1092,"href":"https:\/\/host-unlimited.de\/blog\/wp-json\/wp\/v2\/posts\/1072\/revisions\/1092"}],"wp:attachment":[{"href":"https:\/\/host-unlimited.de\/blog\/wp-json\/wp\/v2\/media?parent=1072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/host-unlimited.de\/blog\/wp-json\/wp\/v2\/categories?post=1072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/host-unlimited.de\/blog\/wp-json\/wp\/v2\/tags?post=1072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}